{"id":1694,"date":"2016-03-09T10:36:09","date_gmt":"2016-03-09T10:36:09","guid":{"rendered":"http:\/\/nitorlack.nitorlack.com\/it\/contacto\/"},"modified":"2023-03-02T16:19:23","modified_gmt":"2023-03-02T14:19:23","slug":"contatto","status":"publish","type":"page","link":"https:\/\/nitorlack.nitorlack.com\/it\/contatto\/","title":{"rendered":"Contatto"},"content":{"rendered":"\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f28363-o1\" lang=\"it-IT\" dir=\"ltr\" data-wpcf7-id=\"28363\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/1694#wpcf7-f28363-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Modulo di contatto\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"28363\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f28363-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><label>Nome e cognome*:<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/label><br \/>\n<label>Email*:<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/label><br \/>\n<label>Telefono:<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-tel\" \/><\/span><\/label><br \/>\n<label>Mensaje:<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span><\/label><br \/>\n<label>Allega il tuo file<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"file-906\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".jpg,.png,.heic,.tif\" aria-invalid=\"false\" type=\"file\" name=\"file-906\" \/><\/span><\/label>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"checkbox-563\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required\"><span class=\"wpcf7-list-item first last\"><label><input type=\"checkbox\" name=\"checkbox-563[]\" value=\"Acconsento al trattamento dei miei dati personali secondo i termini stabiliti nella presente\" \/><span class=\"wpcf7-list-item-label\">Acconsento al trattamento dei miei dati personali secondo i termini stabiliti nella presente<\/span><\/label><\/span><\/span><\/span><a href=\"https:\/\/nitorlack.nitorlack.com\/politica-de-privacidad\/\">Politica sulla riservatezza<\/a><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"checkbox-378\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first last\"><label><input type=\"checkbox\" name=\"checkbox-378[]\" value=\"Acconsento all&#039;utilizzo dei miei dati per ricevere pubblicit\u00e0 dalla tua entit\u00e0\" \/><span class=\"wpcf7-list-item-label\">Acconsento all&#039;utilizzo dei miei dati per ricevere pubblicit\u00e0 dalla tua entit\u00e0<\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Spedire\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"115\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Responsabile<\/td><td>VALRESA COATINGS, S.A<\/td><\/tr><tr><td>Indirizzo postale<\/td><td>Avda. dels Gremis, s\/n. 46190, Riba-roja del Turia (Valencia) Espa\u00f1a.<\/td><\/tr><tr><td>Scopo<\/td><td>Per rispondere alle vostre richieste di informazioni e per fornirvi i nostri servizi.<\/td><\/tr><tr><td>Legittimazione<\/td><td>I suoi dati saranno trattati solo con il suo consenso, selezionando la casella indicata in questo modulo.<\/td><\/tr><tr><td>Destinatari<\/td><td>I vostri dati non saranno trasmessi a terzi.<\/td><\/tr><tr><td>Diritti<\/td><td>\u00c8 possibile accedere ai propri dati, rettificarli, cancellarli e opporsi o limitarne il trattamento contattandoci al nostro indirizzo postale o all&#8217;indirizzo valresa@valresa.com.<\/td><\/tr><tr><td>Ulteriori informazioni<\/td><td>Ulteriori informazioni sono disponibili nella nostra &#8220;Informativa sulla privacy&#8221;.<\/td><\/tr><tr><td>Responsabile della protezione dei dati<\/td><td>Se avete dubbi su come tratteremo i vostri dati o se volete fare un suggerimento o un reclamo, contattate il nostro DPD all&#8217;indirizzo <a href=\"mailto:info@businessadapter.es\">info@businessadapter.es<\/a> o nel <a href=\"https:\/\/www.businessadapter.es\/contacta-con-el-delegado-de-proteccion-de-datos\" rel=\"nofollow\">Formulario de atenci\u00f3n al interesado<\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Responsabile VALRESA COATINGS, S.A Indirizzo postale Avda. dels Gremis, s\/n. 46190, Riba-roja del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1694","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contatto | NitorLACK<\/title>\n<meta name=\"description\" content=\"Nitorlack -Vernice alla nitrocellulosa per chitarre, colori vintage e tutorial su come dipingere la tua chitarra. Scoprire Contatto\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contatto | NitorLACK\" \/>\n<meta property=\"og:description\" content=\"Nitorlack -Vernice alla nitrocellulosa per chitarre, colori vintage e tutorial su come dipingere la tua chitarra. Scoprire Contatto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nitorlack.nitorlack.com\/it\/contatto\/\" \/>\n<meta property=\"og:site_name\" content=\"Nitorlack\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-02T14:19:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/it\\\/contatto\\\/\",\"url\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/it\\\/contatto\\\/\",\"name\":\"Contatto | NitorLACK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/it\\\/#website\"},\"datePublished\":\"2016-03-09T10:36:09+00:00\",\"dateModified\":\"2023-03-02T14:19:23+00:00\",\"description\":\"Nitorlack -Vernice alla nitrocellulosa per chitarre, colori vintage e tutorial su come dipingere la tua chitarra. Scoprire Contatto\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/it\\\/contatto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nitorlack.nitorlack.com\\\/it\\\/contatto\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/it\\\/contatto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Copertina\",\"item\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contatto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/it\\\/\",\"name\":\"Nitorlack\",\"description\":\"Guitar Lacquers\",\"publisher\":{\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/it\\\/#organization\",\"name\":\"Nitorlack\",\"url\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/nitorlack.nitorlack.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/cropped-galleta-negra-1.jpg\",\"contentUrl\":\"http:\\\/\\\/nitorlack.nitorlack.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/cropped-galleta-negra-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Nitorlack\"},\"image\":{\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contatto | NitorLACK","description":"Nitorlack -Vernice alla nitrocellulosa per chitarre, colori vintage e tutorial su come dipingere la tua chitarra. Scoprire Contatto","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Contatto | NitorLACK","og_description":"Nitorlack -Vernice alla nitrocellulosa per chitarre, colori vintage e tutorial su come dipingere la tua chitarra. Scoprire Contatto","og_url":"https:\/\/nitorlack.nitorlack.com\/it\/contatto\/","og_site_name":"Nitorlack","article_modified_time":"2023-03-02T14:19:23+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nitorlack.nitorlack.com\/it\/contatto\/","url":"https:\/\/nitorlack.nitorlack.com\/it\/contatto\/","name":"Contatto | NitorLACK","isPartOf":{"@id":"https:\/\/nitorlack.nitorlack.com\/it\/#website"},"datePublished":"2016-03-09T10:36:09+00:00","dateModified":"2023-03-02T14:19:23+00:00","description":"Nitorlack -Vernice alla nitrocellulosa per chitarre, colori vintage e tutorial su come dipingere la tua chitarra. Scoprire Contatto","breadcrumb":{"@id":"https:\/\/nitorlack.nitorlack.com\/it\/contatto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nitorlack.nitorlack.com\/it\/contatto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nitorlack.nitorlack.com\/it\/contatto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Copertina","item":"https:\/\/nitorlack.nitorlack.com\/it\/"},{"@type":"ListItem","position":2,"name":"Contatto"}]},{"@type":"WebSite","@id":"https:\/\/nitorlack.nitorlack.com\/it\/#website","url":"https:\/\/nitorlack.nitorlack.com\/it\/","name":"Nitorlack","description":"Guitar Lacquers","publisher":{"@id":"https:\/\/nitorlack.nitorlack.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nitorlack.nitorlack.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/nitorlack.nitorlack.com\/it\/#organization","name":"Nitorlack","url":"https:\/\/nitorlack.nitorlack.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nitorlack.nitorlack.com\/it\/#\/schema\/logo\/image\/","url":"http:\/\/nitorlack.nitorlack.com\/wp-content\/uploads\/2016\/02\/cropped-galleta-negra-1.jpg","contentUrl":"http:\/\/nitorlack.nitorlack.com\/wp-content\/uploads\/2016\/02\/cropped-galleta-negra-1.jpg","width":512,"height":512,"caption":"Nitorlack"},"image":{"@id":"https:\/\/nitorlack.nitorlack.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/nitorlack.nitorlack.com\/it\/wp-json\/wp\/v2\/pages\/1694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nitorlack.nitorlack.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nitorlack.nitorlack.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nitorlack.nitorlack.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nitorlack.nitorlack.com\/it\/wp-json\/wp\/v2\/comments?post=1694"}],"version-history":[{"count":0,"href":"https:\/\/nitorlack.nitorlack.com\/it\/wp-json\/wp\/v2\/pages\/1694\/revisions"}],"wp:attachment":[{"href":"https:\/\/nitorlack.nitorlack.com\/it\/wp-json\/wp\/v2\/media?parent=1694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}