{"id":31175,"date":"2020-06-26T09:46:31","date_gmt":"2020-06-26T07:46:31","guid":{"rendered":"http:\/\/nitorlack.nitorlack.com\/blog\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\/"},"modified":"2021-10-07T10:06:47","modified_gmt":"2021-10-07T08:06:47","slug":"vernis-nitrocellulose-tout-ce-que-vous-devez-savoir","status":"publish","type":"post","link":"https:\/\/nitorlack.nitorlack.com\/fr\/blog\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\/","title":{"rendered":"Vernis nitrocellulose: tout ce que vous devez savoir"},"content":{"rendered":"<h3>Qu&rsquo;est-ce qui est vrai dans tous les discours sur la nitrocellulose? Et pourquoi les guitaristes veulent-ils toujours que leurs instruments soient finis avec ce mat\u00e9riau?<\/h3>\n<hr \/>\n<p>Clarence &lsquo;Leo&rsquo; Fender serait intrigu\u00e9 par le march\u00e9 actuel de la guitare. La l\u00e9gende raconte qu&rsquo;il \u00e9tait toujours tourn\u00e9 vers l&rsquo;avenir; Que votre prochaine guitare et les processus utilis\u00e9s pour ce faire s&rsquo;am\u00e9liorent toujours par rapport \u00e0 la derni\u00e8re.<\/p>\n<p>Apr\u00e8s la premi\u00e8re production de Leo il y a 65 ans, de nombreux guitaristes et experts croient passionn\u00e9ment que la nitrocellulose \u00e0 base de solvant \u00e0 paroi mince \u00e0 l&rsquo;ancienne est la meilleure pour le \u00abton\u00bb.<\/p>\n<hr \/>\n<p><strong>Finition nitrocellulose est plus g\u00eanant et prend plus de temps<\/strong> \u00e0 appliquer que les finitions plus courantes comme le polyester ou le polyur\u00e9thane et est moins durable, ce qui signifie que la guitare est beaucoup plus susceptible d&rsquo;avoir des dommages esth\u00e9tiques lors de son voyage \u00e0 travers la cha\u00eene de l&rsquo;approvisionnement et, bien entendu, \u00e0 l&rsquo;usage de son propri\u00e9taire.<\/p>\n<h2>Qui voudrait endommager sa guitare ?<\/h2>\n<p>Je suis s\u00fbr que Leo avec son caract\u00e8re entrepreneurial et productif changerait ce processus pour des finitions plus modernes afin d&rsquo;am\u00e9liorer la production, mais serait-ce mieux pour le \u00ab\u00a0ton\u00a0\u00bb?<\/p>\n<p>Les d\u00e9tracteurs soutiennent qu&rsquo;il s&rsquo;agit de pure nostalgie, les amateurs de cette finition veillent \u00e0 ce que:<\/p>\n<p><strong>\u00ab\u00a0La guitare vieillit mieux et continuera de\u00a0\u00bb durcir \u00ab\u00a0pendant des ann\u00e9es, car le solvant dans la finition continue de s&rsquo;\u00e9vaporer et de durcir\u00a0\u00bb<\/strong><\/p>\n<p>Quoi qu&rsquo;il en soit, les faits sont que Fender a utilis\u00e9 \u00e0 la fois la <strong>laque acrylique et la nitrocellulose<\/strong> entre les finitions 1950 et 60 Normes et Couleurs personnalis\u00e9es.<\/p>\n<p>D\u00e9velopp\u00e9 \u00e0 l&rsquo;origine pour les voitures de l&rsquo;\u00e9poque, vous pouvez identifier lequel est par les codes de peinture Dupont associ\u00e9s, qui sont d\u00e9finis avec &lsquo;Lucite&rsquo; (acrylique) ou &lsquo;Duco&rsquo; (nitrocellulose).<\/p>\n<p>Le Lake Placid Blue (Lucite 2876-L), par exemple, est en acrylique, tandis que le Sonic Blue \u00e9tait en nitrocellulose (Duco 2295). Les finitions translucides \u00e9taient toujours nitro, mais toutes les couleurs n&rsquo;avaient pas de finitions translucides; Si vous voyez une Strat blanche avec une nuance de jaune, par exemple, elle a probablement une couche transparente de nitrocellulose. S&rsquo;il semble toujours tr\u00e8s \u00ab\u00a0blanc\u00a0\u00bb, il y a de fortes chances qu&rsquo;il n&rsquo;y ait pas de top coat.<\/p>\n<p>Le m\u00eame effet se produit sur les guitares finies en Lake Placid Blue qui peuvent para\u00eetre plus vertes avec l&rsquo;\u00e2ge. En fait, les <strong>peintures acryliques<\/strong> ont \u00e9t\u00e9 d\u00e9velopp\u00e9es parce qu&rsquo;elles \u00e9taient plus r\u00e9sistantes au jaunissement et ne craquaient pas comme les <strong>finitions nitrocellulosiques<\/strong>. Les finitions nitro, cependant, avaient un brillant beaucoup plus intense.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10396 size-full\" src=\"https:\/\/nitorlack.nitorlack.com\/wp-content\/uploads\/2016\/11\/lacquer-jazzes-650-80.jpg\" alt=\"informations sur les finitions en nitrocellulose\" width=\"650\" height=\"487\" srcset=\"https:\/\/nitorlack.nitorlack.com\/wp-content\/uploads\/2016\/11\/lacquer-jazzes-650-80.jpg 650w, https:\/\/nitorlack.nitorlack.com\/wp-content\/uploads\/2016\/11\/lacquer-jazzes-650-80-160x120.jpg 160w, https:\/\/nitorlack.nitorlack.com\/wp-content\/uploads\/2016\/11\/lacquer-jazzes-650-80-220x165.jpg 220w, https:\/\/nitorlack.nitorlack.com\/wp-content\/uploads\/2016\/11\/lacquer-jazzes-650-80-640x480.jpg 640w, https:\/\/nitorlack.nitorlack.com\/wp-content\/uploads\/2016\/11\/lacquer-jazzes-650-80-300x225.jpg 300w, https:\/\/nitorlack.nitorlack.com\/wp-content\/uploads\/2016\/11\/lacquer-jazzes-650-80-500x375.jpg 500w, https:\/\/nitorlack.nitorlack.com\/wp-content\/uploads\/2016\/11\/lacquer-jazzes-650-80-267x200.jpg 267w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/p>\n<p>Deux jazzmasters Lake Placid Blue des ann\u00e9es 60 &#8211; mais la guitare gauche a une couche de finition nitro, qui a jauni au fil du temps<\/p>\n<h2>La nitrocellulose et le temps qui passe<\/h2>\n<p>Les <strong>composants en nitrocellulose<\/strong> et en acrylique doivent \u00eatre m\u00e9lang\u00e9s dans un solvant pour \u00eatre correctement pulv\u00e9ris\u00e9s sur une guitare ou m\u00eame une automobile.<\/p>\n<p>Une fois appliqu\u00e9e en plusieurs couches pendant des jours (chaque m\u00e9lange avec le suivant, \u00e9liminant consid\u00e9rablement le besoin de pon\u00e7age intercouche), la guitare peut s\u00e9cher avant de finalement polir. Comme nous le savons maintenant, cette guitare continuera \u00e0 \u00abdurcir\u00bb pendant des ann\u00e9es \u00e0 venir, car le solvant dans la finition continuera de s&rsquo;\u00e9vaporer et de durcir.<\/p>\n<p>Sur certaines guitares, cela n&rsquo;a jamais vraiment fonctionn\u00e9 et la finition est lisse, mais si vous regardez la plupart des Fender des ann\u00e9es 1950 ou du d\u00e9but des ann\u00e9es 1960, la finition est souvent extr\u00eamement mince et presque fusionn\u00e9e avec du bois.<\/p>\n<p>Les diff\u00e9rences de produits chimiques et de pigments de couleur utilis\u00e9s aujourd&rsquo;hui en raison des exigences environnementales rendent les guitares Fender entre 50 et 65 si pr\u00e9cieuses et \u00e0 collectionner.<\/p>\n<p><strong>\u00ab\u00a0Les finitions nitro modernes ne sont plus exactement comme avant, bien qu&rsquo;elles diff\u00e8rent un peu, mais elles sont toujours meilleures pour le son que les finitions en polyester actuelles de nombreuses guitares de s\u00e9rie\u00a0\u00bb<\/strong><\/p>\n<p>En raison des exigences environnementales des diff\u00e9rents pays pour les usines de guitares, ainsi que de la n\u00e9cessit\u00e9 de r\u00e9duire les co\u00fbts de production, beaucoup d&rsquo;entre elles (y compris Fender) ont opt\u00e9 pour des finitions plus modernes et actuelles telles que les polyur\u00e9thanes et le polyester.<\/p>\n<p><strong>L&rsquo;inconv\u00e9nient est qu&rsquo;ils ne se sentent pas ou ne ressemblent pas \u00e0 des finitions vintage,<\/strong> et ils ne vieillissent certainement pas comme ils le font &#8211; <em>avez-vous d\u00e9j\u00e0 essay\u00e9 de \u00ab\u00a0relic\u00a0\u00bb sur du polyester moderne? C&rsquo;est comme rayer le verre.<\/em><\/p>\n<p>Beaucoup de gens verraient cela comme un \u00e9norme avantage &#8211; le regrett\u00e9 Leo Fender inclus &#8211; parce que sa guitare est encore brillante et neuve, beaucoup plus longue. Pour certains, cependant, <strong>une guitare sans finition nitrocellulose n&rsquo;est pas une guitare.<\/strong><\/p>\n<p>Les finitions modernes en nitrocellulose de Fender ne sont pas exactement les m\u00eames que les anciennes. Il y a des centaines de discussions dans les forums internationaux sur les sous-couches et sous-couches en polyur\u00e9thane et polyester sous nitrocellulose\u2026 le soi-disant (Fender fullerplast)<\/p>\n<p>Fender affirme que le processus de finition utilis\u00e9 dans les nouveaux instruments d&rsquo;Ensenada est une sous-couche \/ scellant en polyester, suivi de cinq couches de laque nitrocellulosique \u00e0 haute teneur en solides Seagrave L-4540 pour la couleur et les couches de finition.<\/p>\n<h2>Alors pourquoi la nitrocellulose?<\/h2>\n<p>En bannissant compl\u00e8tement les finitions en polyester, une bonne finition en polyur\u00e9thane avec juste la bonne \u00e9paisseur peut nous donner un bon son avec une finition durable.<\/p>\n<p>Mais si nous voulons le look vintage des finitions Fender vintage et le vieillissement progressif de notre instrument, nous avons absolument besoin d&rsquo;une <strong>finition nitrocellulose.<\/strong><\/p>\n<h3>\u00c0 mon avis, la nitrocellulose:<\/h3>\n<h3>\u00ab\u00a0Sonne mieux, vieillit mieux et se sent mieux\u00a0\u00bb<\/h3>\n<hr \/>\n<div class=\"lmt__side_container lmt__side_container--target df2217\">\n<div class=\"lmt__textarea_container df1966__increase_padding focus lmt__textarea_container--focus\">\n<div class=\"lmt__inner_textarea_container\" title=\"Haz clic en una palabra para mostrar traducciones alternativas\">\n<div class=\"lmt__textarea_base_style\">Enfin, nous souhaitons mentionner les produits que nous proposons sur <a href=\"https:\/\/nitorlack.nitorlack.com\/fr\/\">notre site,<\/a> sp\u00e9cialement con\u00e7us pour le bois de guitare, avec eux vous obtiendrez un r\u00e9sultat de qualit\u00e9 si vous suivez les \u00e9tapes telles que d\u00e9taill\u00e9es dans cet <a href=\"https:\/\/nitorlack.nitorlack.com\/fr\/blog\/comment-peindre-une-guitare-en-vernis-nitrocellulosique-a-partir-de-zero-etape-par-etape\/\">article de notre blog.<\/a><\/div>\n<\/div>\n<div class=\"lmt__ad_charLimit_container\"><\/div>\n<div class=\"lmt__loadingIndicator_container\"><\/div>\n<div class=\"lmt__translations_as_text\"><\/div>\n<div class=\"lmt__formalitySwitch_ad_container_desktop\"><\/div>\n<div class=\"lmt__target_toolbar lmt__target_toolbar--visible\">\n<div class=\"lmt__speaker_container\"><\/div>\n<div class=\"lmt_targetToolbar__appPromotion_container\"><\/div>\n<div class=\"lmt__target_toolbar__copy_container\"><\/div>\n<div class=\"lmt__target_toolbar__share_container\"><\/div>\n<div class=\"lmt__rating_container\">\n<div class=\"lmt__rating \"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"targetHighlightTooltipPortal\"><\/div>\n<div class=\"lmt__formalitySwitch_feedback_container\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Qu&rsquo;est-ce qui est vrai dans tous les discours sur la nitrocellulose? Et pourquoi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10396,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[7503],"tags":[],"class_list":["post-31175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vernis nitrocellulose: tout ce que vous devez savoir | NitorLACK<\/title>\n<meta name=\"description\" content=\"Tout ce que vous devez savoir sur la peinture nitrocellulosique, secrets, application, caract\u00e9ristiques et propri\u00e9t\u00e9s. d\u00e9couvrez comment vernir votre guitare avec la nitrocellulose pour guitare utilis\u00e9e par les professionnels. Nitrocellulose vintage qui respecte le son de la guitare.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vernis nitrocellulose: tout ce que vous devez savoir | NitorLACK\" \/>\n<meta property=\"og:description\" content=\"Tout ce que vous devez savoir sur la peinture nitrocellulosique, secrets, application, caract\u00e9ristiques et propri\u00e9t\u00e9s. d\u00e9couvrez comment vernir votre guitare avec la nitrocellulose pour guitare utilis\u00e9e par les professionnels. Nitrocellulose vintage qui respecte le son de la guitare.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nitorlack.nitorlack.com\/fr\/blog\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\/\" \/>\n<meta property=\"og:site_name\" content=\"Nitorlack\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-26T07:46:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-07T08:06:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nitorlack.nitorlack.com\/wp-content\/uploads\/2016\/11\/lacquer-jazzes-650-80.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rubenparre\u00f1operez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rubenparre\u00f1operez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/blog\\\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/blog\\\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\\\/\"},\"author\":{\"name\":\"Rubenparre\u00f1operez\",\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/#\\\/schema\\\/person\\\/2a7423841a35f06e8b6d566bb1385ae2\"},\"headline\":\"Vernis nitrocellulose: tout ce que vous devez savoir\",\"datePublished\":\"2020-06-26T07:46:31+00:00\",\"dateModified\":\"2021-10-07T08:06:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/blog\\\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\\\/\"},\"wordCount\":1039,\"publisher\":{\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/blog\\\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/lacquer-jazzes-650-80.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/blog\\\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\\\/\",\"url\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/blog\\\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\\\/\",\"name\":\"Vernis nitrocellulose: tout ce que vous devez savoir | NitorLACK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/blog\\\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/blog\\\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/lacquer-jazzes-650-80.jpg\",\"datePublished\":\"2020-06-26T07:46:31+00:00\",\"dateModified\":\"2021-10-07T08:06:47+00:00\",\"description\":\"Tout ce que vous devez savoir sur la peinture nitrocellulosique, secrets, application, caract\u00e9ristiques et propri\u00e9t\u00e9s. d\u00e9couvrez comment vernir votre guitare avec la nitrocellulose pour guitare utilis\u00e9e par les professionnels. Nitrocellulose vintage qui respecte le son de la guitare.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/blog\\\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/blog\\\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/blog\\\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/lacquer-jazzes-650-80.jpg\",\"contentUrl\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/lacquer-jazzes-650-80.jpg\",\"width\":650,\"height\":487},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/blog\\\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Page de Couverture\",\"item\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vernis nitrocellulose: tout ce que vous devez savoir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/\",\"name\":\"Nitorlack\",\"description\":\"Guitar Lacquers\",\"publisher\":{\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/#organization\",\"name\":\"Nitorlack\",\"url\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/nitorlack.nitorlack.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/cropped-galleta-negra-1.jpg\",\"contentUrl\":\"http:\\\/\\\/nitorlack.nitorlack.com\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/cropped-galleta-negra-1.jpg\",\"width\":512,\"height\":512,\"caption\":\"Nitorlack\"},\"image\":{\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nitorlack.nitorlack.com\\\/fr\\\/#\\\/schema\\\/person\\\/2a7423841a35f06e8b6d566bb1385ae2\",\"name\":\"Rubenparre\u00f1operez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b8569580eabd4ddc08180180c3898b0f1b137687426dcc2362d5f3d3483f5d05?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b8569580eabd4ddc08180180c3898b0f1b137687426dcc2362d5f3d3483f5d05?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b8569580eabd4ddc08180180c3898b0f1b137687426dcc2362d5f3d3483f5d05?s=96&d=mm&r=g\",\"caption\":\"Rubenparre\u00f1operez\"},\"sameAs\":[\"https:\\\/\\\/nitorlack.nitorlack.com\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vernis nitrocellulose: tout ce que vous devez savoir | NitorLACK","description":"Tout ce que vous devez savoir sur la peinture nitrocellulosique, secrets, application, caract\u00e9ristiques et propri\u00e9t\u00e9s. d\u00e9couvrez comment vernir votre guitare avec la nitrocellulose pour guitare utilis\u00e9e par les professionnels. Nitrocellulose vintage qui respecte le son de la guitare.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Vernis nitrocellulose: tout ce que vous devez savoir | NitorLACK","og_description":"Tout ce que vous devez savoir sur la peinture nitrocellulosique, secrets, application, caract\u00e9ristiques et propri\u00e9t\u00e9s. d\u00e9couvrez comment vernir votre guitare avec la nitrocellulose pour guitare utilis\u00e9e par les professionnels. Nitrocellulose vintage qui respecte le son de la guitare.","og_url":"https:\/\/nitorlack.nitorlack.com\/fr\/blog\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\/","og_site_name":"Nitorlack","article_published_time":"2020-06-26T07:46:31+00:00","article_modified_time":"2021-10-07T08:06:47+00:00","og_image":[{"width":650,"height":487,"url":"https:\/\/nitorlack.nitorlack.com\/wp-content\/uploads\/2016\/11\/lacquer-jazzes-650-80.jpg","type":"image\/jpeg"}],"author":"Rubenparre\u00f1operez","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Rubenparre\u00f1operez","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nitorlack.nitorlack.com\/fr\/blog\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\/#article","isPartOf":{"@id":"https:\/\/nitorlack.nitorlack.com\/fr\/blog\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\/"},"author":{"name":"Rubenparre\u00f1operez","@id":"https:\/\/nitorlack.nitorlack.com\/fr\/#\/schema\/person\/2a7423841a35f06e8b6d566bb1385ae2"},"headline":"Vernis nitrocellulose: tout ce que vous devez savoir","datePublished":"2020-06-26T07:46:31+00:00","dateModified":"2021-10-07T08:06:47+00:00","mainEntityOfPage":{"@id":"https:\/\/nitorlack.nitorlack.com\/fr\/blog\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\/"},"wordCount":1039,"publisher":{"@id":"https:\/\/nitorlack.nitorlack.com\/fr\/#organization"},"image":{"@id":"https:\/\/nitorlack.nitorlack.com\/fr\/blog\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\/#primaryimage"},"thumbnailUrl":"https:\/\/nitorlack.nitorlack.com\/wp-content\/uploads\/2016\/11\/lacquer-jazzes-650-80.jpg","articleSection":["Blog"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/nitorlack.nitorlack.com\/fr\/blog\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\/","url":"https:\/\/nitorlack.nitorlack.com\/fr\/blog\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\/","name":"Vernis nitrocellulose: tout ce que vous devez savoir | NitorLACK","isPartOf":{"@id":"https:\/\/nitorlack.nitorlack.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nitorlack.nitorlack.com\/fr\/blog\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\/#primaryimage"},"image":{"@id":"https:\/\/nitorlack.nitorlack.com\/fr\/blog\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\/#primaryimage"},"thumbnailUrl":"https:\/\/nitorlack.nitorlack.com\/wp-content\/uploads\/2016\/11\/lacquer-jazzes-650-80.jpg","datePublished":"2020-06-26T07:46:31+00:00","dateModified":"2021-10-07T08:06:47+00:00","description":"Tout ce que vous devez savoir sur la peinture nitrocellulosique, secrets, application, caract\u00e9ristiques et propri\u00e9t\u00e9s. d\u00e9couvrez comment vernir votre guitare avec la nitrocellulose pour guitare utilis\u00e9e par les professionnels. Nitrocellulose vintage qui respecte le son de la guitare.","breadcrumb":{"@id":"https:\/\/nitorlack.nitorlack.com\/fr\/blog\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nitorlack.nitorlack.com\/fr\/blog\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nitorlack.nitorlack.com\/fr\/blog\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\/#primaryimage","url":"https:\/\/nitorlack.nitorlack.com\/wp-content\/uploads\/2016\/11\/lacquer-jazzes-650-80.jpg","contentUrl":"https:\/\/nitorlack.nitorlack.com\/wp-content\/uploads\/2016\/11\/lacquer-jazzes-650-80.jpg","width":650,"height":487},{"@type":"BreadcrumbList","@id":"https:\/\/nitorlack.nitorlack.com\/fr\/blog\/vernis-nitrocellulose-tout-ce-que-vous-devez-savoir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Page de Couverture","item":"https:\/\/nitorlack.nitorlack.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Vernis nitrocellulose: tout ce que vous devez savoir"}]},{"@type":"WebSite","@id":"https:\/\/nitorlack.nitorlack.com\/fr\/#website","url":"https:\/\/nitorlack.nitorlack.com\/fr\/","name":"Nitorlack","description":"Guitar Lacquers","publisher":{"@id":"https:\/\/nitorlack.nitorlack.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nitorlack.nitorlack.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/nitorlack.nitorlack.com\/fr\/#organization","name":"Nitorlack","url":"https:\/\/nitorlack.nitorlack.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nitorlack.nitorlack.com\/fr\/#\/schema\/logo\/image\/","url":"http:\/\/nitorlack.nitorlack.com\/wp-content\/uploads\/2016\/02\/cropped-galleta-negra-1.jpg","contentUrl":"http:\/\/nitorlack.nitorlack.com\/wp-content\/uploads\/2016\/02\/cropped-galleta-negra-1.jpg","width":512,"height":512,"caption":"Nitorlack"},"image":{"@id":"https:\/\/nitorlack.nitorlack.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/nitorlack.nitorlack.com\/fr\/#\/schema\/person\/2a7423841a35f06e8b6d566bb1385ae2","name":"Rubenparre\u00f1operez","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b8569580eabd4ddc08180180c3898b0f1b137687426dcc2362d5f3d3483f5d05?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b8569580eabd4ddc08180180c3898b0f1b137687426dcc2362d5f3d3483f5d05?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b8569580eabd4ddc08180180c3898b0f1b137687426dcc2362d5f3d3483f5d05?s=96&d=mm&r=g","caption":"Rubenparre\u00f1operez"},"sameAs":["https:\/\/nitorlack.nitorlack.com\/"]}]}},"_links":{"self":[{"href":"https:\/\/nitorlack.nitorlack.com\/fr\/wp-json\/wp\/v2\/posts\/31175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nitorlack.nitorlack.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nitorlack.nitorlack.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nitorlack.nitorlack.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nitorlack.nitorlack.com\/fr\/wp-json\/wp\/v2\/comments?post=31175"}],"version-history":[{"count":0,"href":"https:\/\/nitorlack.nitorlack.com\/fr\/wp-json\/wp\/v2\/posts\/31175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nitorlack.nitorlack.com\/fr\/wp-json\/wp\/v2\/media\/10396"}],"wp:attachment":[{"href":"https:\/\/nitorlack.nitorlack.com\/fr\/wp-json\/wp\/v2\/media?parent=31175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nitorlack.nitorlack.com\/fr\/wp-json\/wp\/v2\/categories?post=31175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nitorlack.nitorlack.com\/fr\/wp-json\/wp\/v2\/tags?post=31175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}